{"id":7162,"date":"2026-05-13T11:53:01","date_gmt":"2026-05-13T14:53:01","guid":{"rendered":"https:\/\/jornalnossahistoria.com.br\/portal\/index.php\/2026\/05\/13\/uberlandia-aperta-cerco-contra-geradores-de-lixo\/"},"modified":"2026-05-13T11:53:01","modified_gmt":"2026-05-13T14:53:01","slug":"uberlandia-aperta-cerco-contra-geradores-de-lixo","status":"publish","type":"post","link":"https:\/\/jornalnossahistoria.com.br\/portal\/index.php\/2026\/05\/13\/uberlandia-aperta-cerco-contra-geradores-de-lixo\/","title":{"rendered":"Uberl\u00e2ndia aperta cerco contra geradores de lixo"},"content":{"rendered":"<p><em><span>Foto: Tony Winston\/Ag\u00eancia Bras\u00edlia<\/span><\/em><\/p>\n<p><strong><span>COLUNA MG<\/span><\/strong><br \/><span>Principais destaques dos jornais e portais integrantes da Rede Sindijori MG<\/span><br \/><span><a href=\"https:\/\/www.sindijorimg.com.br\/\">www.sindijorimg.com.br<\/a><\/span><\/p>\n<p><strong><span><\/span><\/strong><\/p>\n<p><strong><span>Uberl\u00e2ndia aperta cerco contra geradores de lixo<\/span><\/strong><br \/><span>A Prefeitura de Uberl\u00e2ndia publicou decreto que estabelece normas r\u00edgidas para os chamados \u201cgrandes geradores\u201d de res\u00edduos s\u00f3lidos. A partir de agora, qualquer estabelecimento que produza mais de 200 litros de lixo por dia deve assumir a responsabilidade total pelo manejo, transporte e destina\u00e7\u00e3o final do material. A medida visa priorizar a reciclagem e aliviar o sistema de coleta p\u00fablica municipal. De acordo com o documento, os grandes geradores precisam elaborar o Plano de Gerenciamento de Res\u00edduos S\u00f3lidos (O Regionalz\u00e3o).<\/span><br \/><span><a href=\"https:\/\/regionalzao.com.br\/cotidiano\/uberlandia-aperta-cerco-contra-grandes-geradores-de-lixo\/\">https:\/\/regionalzao.com.br\/cotidiano\/uberlandia-aperta-cerco-contra-grandes-geradores-de-lixo\/<\/a><\/span><\/p>\n<p><strong><span><\/span><\/strong><\/p>\n<p><strong><span>Uso de drogas gera multa em BH<\/span><\/strong><br \/><span>A C\u00e2mara Municipal de Belo Horizonte aprovou em 2\u00ba turno o Projeto que prev\u00ea multa de R$ 1,5 mil para pessoas flagradas consumindo ou portando drogas il\u00edcitas em espa\u00e7os p\u00fablicos da capital. O texto recebeu 26 votos favor\u00e1veis, oito contr\u00e1rios e duas absten\u00e7\u00f5es. Agora, a proposta segue para an\u00e1lise do prefeito \u00c1lvaro Dami\u00e3o, que poder\u00e1 sancionar ou vetar o projeto. A proposta estabelece puni\u00e7\u00e3o administrativa para quem for flagrado usando ou portando drogas em locais p\u00fablicos como ruas, avenidas, pra\u00e7as, campos de futebol, entre outros espa\u00e7os p\u00fablicos. (Por Dentro de Minas)<\/span><br \/><span><a href=\"https:\/\/pordentrodeminas.com.br\/\">https:\/\/pordentrodeminas.com.br<\/a><\/span><\/p>\n<p><strong><span><\/span><\/strong><\/p>\n<p><strong><span>PL descarta Professor Mateus Sim\u00f5es<\/span><\/strong><br \/><span>O Partido Liberal decidiu intensificar as articula\u00e7\u00f5es com o senador Cleitinho Azevedo visando a disputa pelo governo de Minas Gerais nas elei\u00e7\u00f5es de 2026. A defini\u00e7\u00e3o ocorreu durante reuni\u00e3o da c\u00fapula nacional da legenda realizada nesta ter\u00e7a-feira, em Bras\u00edlia. Com a decis\u00e3o, a possibilidade de composi\u00e7\u00e3o com o vice-governador Mateus Sim\u00f5es foi descartada pelo partido. A avalia\u00e7\u00e3o interna \u00e9 de que h\u00e1 incompatibilidade pol\u00edtica no cen\u00e1rio nacional, uma vez que Sim\u00f5es integra o grupo pol\u00edtico do governador Romeu Zema, apontado como poss\u00edvel pr\u00e9-candidato \u00e0 Presid\u00eancia da Rep\u00fablica pelo Partido Novo. (Em Tempo)<\/span><br \/><span><a href=\"https:\/\/jornalemtempo.com\/pl-descarta-professor-mateus-simoes\">https:\/\/jornalemtempo.com\/pl-descarta-professor-mateus-simoes<\/a><\/span><\/p>\n<p><strong><span><\/span><\/strong><\/p>\n<p><strong><span>Itabira recebe Giro Pela Regional<\/span><\/strong><br \/><span>A Fiemg Regional Vale do A\u00e7o, em parceria com o Sindimiva, realiza no dia 21 de maio, em Itabira, mais uma edi\u00e7\u00e3o do Giro pela Regional, iniciativa que tem como objetivo fortalecer o ambiente de neg\u00f3cios, gerar conex\u00f5es estrat\u00e9gicas e impulsionar o desenvolvimento da ind\u00fastria local e regional. O evento acontecer\u00e1 na Associa\u00e7\u00e3o Comercial, Industrial, de Servi\u00e7os e Agroneg\u00f3cios de Itabira \u2013 Acita e contar\u00e1 com uma programa\u00e7\u00e3o voltada a empres\u00e1rios, gestores e profissionais da ind\u00fastria. (Portal Carlos Souto)<\/span><br \/><span><a href=\"https:\/\/www.portalcarlossouto.com.br\/noticias\/regional\/fiemg-vale-do-aco-e-sindimiva-promovem-giro-pela-regional-em-itabira\/\">https:\/\/www.portalcarlossouto.com.br\/noticias\/regional\/fiemg-vale-do-aco-e-sindimiva-promovem-giro-pela-regional-em-itabira\/<\/a><\/span><\/p>\n<p><strong><span><\/span><\/strong><\/p>\n<p><strong><span>Santa Rita atrai milhares de devotos<\/span><\/strong><br \/><span>O Santu\u00e1rio de Santa Rita de C\u00e1ssia, em C\u00e1ssia (MG), inicia neste dia 13 de maio a quarta edi\u00e7\u00e3o da Novena e Festa em honra \u00e0 sua padroeira, conhecida mundialmente como a &#8220;Santa das Causas Imposs\u00edveis&#8221;. Inaugurado em maio de 2022 e detentor do t\u00edtulo de maior santu\u00e1rio do mundo dedicado \u00e0 santa, o local se consolidou como um dos epicentros da f\u00e9 cat\u00f3lica no Brasil, atraindo peregrinos de todos os estados. Este ano, as celebra\u00e7\u00f5es seguem o lema \u201cPeregrinos no tempo e em comunh\u00e3o com a Igreja do c\u00e9u\u201d, inspirado nas diretrizes do S\u00ednodo dos Bispos. (Observo)<\/span><br \/><span><a href=\"https:\/\/www.observo.com.br\/santuario-de-santa-rita-inicia-nesta-quarta-novena-e-festa-em-cassia\">https:\/\/www.observo.com.br\/santuario-de-santa-rita-inicia-nesta-quarta-novena-e-festa-em-cassia<\/a><\/span><\/p>\n<p><strong><span><\/span><\/strong><\/p>\n<p><strong><span>Usipa ter\u00e1 Encontro de Neg\u00f3cios<\/span><\/strong><br \/><span>A for\u00e7a da ind\u00fastria nacional e internacional j\u00e1 tem presen\u00e7a confirmada no 19\u00ba Encontro de Neg\u00f3cios da Expo Usipa. Reconhecido como um dos principais ambientes de conex\u00e3o empresarial do setor industrial em Minas Gerais e do pa\u00eds, o encontro reunir\u00e1 grandes empresas \u00e2ncoras que movimentam importantes cadeias produtivas do pa\u00eds e ampliam as oportunidades de networking, parcerias estrat\u00e9gicas e gera\u00e7\u00e3o de neg\u00f3cios durante a feira. Entre as empresas \u00e2ncoras confirmadas para esta edi\u00e7\u00e3o est\u00e3o a Aperam, ArcelorMittal, Bemisa, Braskem, Cenibra, CSN, Ferroeste, Jaguar Mining, Ternium, Usiminas, Vale, Vallourec e VLI. (Portal Silmara de Freitas)<\/span><br \/><span><a href=\"https:\/\/www.silmaradefreitas.com.br\/19o-encontro-de-negocios-da-expo-usipa-reunira-grandes-empresas-ancoras-da-industria\/\">https:\/\/www.silmaradefreitas.com.br\/19o-encontro-de-negocios-da-expo-usipa-reunira-grandes-empresas-ancoras-da-industria\/<\/a><\/span><\/p>\n<p><span><\/span><\/p>\n<p><strong><span>Sul de Minas registra primeira geada do ano<\/span><\/strong><br \/><span>Com temperaturas abaixo de zero, o Sul de Minas registrou na manh\u00e3 de ter\u00e7a-feira (12) a primeira geada do outono. O fen\u00f4meno foi mais intenso na regi\u00e3o da Serra da Mantiqueira, onde os term\u00f4metros marcaram valores pr\u00f3ximos ou abaixo de zero grau. A menor temperatura foi registrada em Delfim Moreira, munic\u00edpio vizinho a Itajub\u00e1, que atingiu -3,1\u00b0C. Ainda na regi\u00e3o serrana, Monte Verde e Camanducaia registraram 0,1\u00b0C, enquanto Maria da F\u00e9, tamb\u00e9m pr\u00f3xima a Itajub\u00e1, anotou 2,2\u00b0C. A onda de frio chegou de forma definitiva ao outono no Sul de Minas, afetando tamb\u00e9m cidades de menor altitude. (O Debate)<\/span><br \/><span><a href=\"https:\/\/www.odebatenoticias.com.br\/post\/sul-de-minas-registra-primeira-geada-do-outono-com-temperaturas-abaixo-de-zero\">https:\/\/www.odebatenoticias.com.br\/post\/sul-de-minas-registra-primeira-geada-do-outono-com-temperaturas-abaixo-de-zero<\/a><\/span><\/p>\n<p><span><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Foto: Tony Winston\/Ag\u00eancia Bras\u00edlia COLUNA MGPrincipais destaques dos jornais e portais integrantes da Rede Sindijori MGwww.sindijorimg.com.br Uberl\u00e2ndia aperta cerco contra geradores de lixoA Prefeitura de Uberl\u00e2ndia<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":7163,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[50],"tags":[],"class_list":["post-7162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coluna_mg"],"aioseo_notices":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/jornalnossahistoria.com.br\/portal\/index.php\/wp-json\/wp\/v2\/posts\/7162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalnossahistoria.com.br\/portal\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalnossahistoria.com.br\/portal\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalnossahistoria.com.br\/portal\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalnossahistoria.com.br\/portal\/index.php\/wp-json\/wp\/v2\/comments?post=7162"}],"version-history":[{"count":0,"href":"https:\/\/jornalnossahistoria.com.br\/portal\/index.php\/wp-json\/wp\/v2\/posts\/7162\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalnossahistoria.com.br\/portal\/index.php\/wp-json\/wp\/v2\/media\/7163"}],"wp:attachment":[{"href":"https:\/\/jornalnossahistoria.com.br\/portal\/index.php\/wp-json\/wp\/v2\/media?parent=7162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalnossahistoria.com.br\/portal\/index.php\/wp-json\/wp\/v2\/categories?post=7162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalnossahistoria.com.br\/portal\/index.php\/wp-json\/wp\/v2\/tags?post=7162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}